{"id":452,"date":"2026-07-09T17:24:00","date_gmt":"2026-07-09T15:24:00","guid":{"rendered":"https:\/\/usequalitylube.com\/imprint\/"},"modified":"2024-01-13T11:53:55","modified_gmt":"2024-01-13T10:53:55","slug":"imprint","status":"publish","type":"page","link":"https:\/\/usequalitylube.com\/pt-pt\/imprint\/","title":{"rendered":"Imprint"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; background_enable_image=&#8221;off&#8221; background_position=&#8221;center_left&#8221; background_horizontal_offset=&#8221;49%&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;-143px||-120px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;25px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row module_id=&#8221;erkennen&#8221; module_class=&#8221;erkennen&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||-36px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;Agrandir|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#060a20&#8243; header_2_font_size=&#8221;40px&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;29px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Imprint<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>pjur group Luxembourg S.A.<br \/>87, Esplanade de la Moselle<br \/>6637 Wasserbillig<br \/>Luxembourg<\/p>\n<p>Tel.: +352 74 89 89<br \/>Email: info@pjur.com<\/p>\n<p>Commercial Register: Registre de Commerce et des Soci\u00e9t\u00e9s Luxembourg<br \/>Registration Number: B 57423<\/p>\n<p>Administrator: Alexander Giebel<\/p>\n<p>VAT Identification Number: LU16931335<\/p>\n<p>Platform of the EU Commission for online dispute resolution: <a href=\"https:\/\/ec.europa.eu\/odr\">https:\/\/ec.europa.eu\/odr<\/a><\/p>\n<p>We are neither obligated nor willing to participate in dispute resolution proceedings before a consumer arbitration board.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f7f7f7&#8243; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Proxima Nova Light|300|||on||||&#8221; text_text_color=&#8221;#060a20&#8243; text_font_size=&#8221;18px&#8221; text_orientation=&#8221;right&#8221; custom_margin=&#8221;11px||||false|false&#8221; link_option_url=&#8221;https:\/\/www.pjurlove.com\/impressum\/&#8221; link_option_url_new_window=&#8221;on&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;center&#8221; text_orientation_phone=&#8221;&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><a href=\"https:\/\/usequalitylube.com\/pt-pt\/imprint\/\">Ficha T\u00e9cnica<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Proxima Nova Light|300|||on||||&#8221; text_text_color=&#8221;#060a20&#8243; text_font_size=&#8221;18px&#8221; custom_margin=&#8221;11px||||false|false&#8221; link_option_url=&#8221;https:\/\/www.pjurlove.com\/datenschutzerklaerung\/&#8221; link_option_url_new_window=&#8221;on&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;center&#8221; text_orientation_phone=&#8221;center&#8221; text_orientation_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p><a href=\"https:\/\/usequalitylube.com\/pt-pt\/privacy-policy\/\">Prote\u00e7\u00e3o de dados<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|auto|-138px|auto||&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;||-36px||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/usequalitylube.com\/wp-content\/uploads\/2023\/11\/logo-feel.png&#8221; title_text=&#8221;logo feel&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;35%&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imprintpjur group Luxembourg S.A.87, Esplanade de la Moselle6637 WasserbilligLuxembourg Tel.: +352 74 89 89Email: info@pjur.com Commercial Register: Registre de Commerce et des Soci\u00e9t\u00e9s LuxembourgRegistration Number: B 57423 Administrator: Alexander Giebel VAT Identification Number: LU16931335 Platform of the EU Commission for online dispute resolution: https:\/\/ec.europa.eu\/odr We are neither obligated nor willing to participate in dispute resolution [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-452","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/usequalitylube.com\/pt-pt\/wp-json\/wp\/v2\/pages\/452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/usequalitylube.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/usequalitylube.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/usequalitylube.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/usequalitylube.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=452"}],"version-history":[{"count":1,"href":"https:\/\/usequalitylube.com\/pt-pt\/wp-json\/wp\/v2\/pages\/452\/revisions"}],"predecessor-version":[{"id":512,"href":"https:\/\/usequalitylube.com\/pt-pt\/wp-json\/wp\/v2\/pages\/452\/revisions\/512"}],"wp:attachment":[{"href":"https:\/\/usequalitylube.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}